{"id":2813,"date":"2022-07-05T18:36:49","date_gmt":"2022-07-05T18:36:49","guid":{"rendered":"https:\/\/somossalud.us\/project\/guia-vacunas-recomendadas-para-ninos\/"},"modified":"2022-07-06T22:15:57","modified_gmt":"2022-07-06T22:15:57","slug":"guide-recommended-vaccines-for-children","status":"publish","type":"project","link":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/","title":{"rendered":"Guide: Recommended Vaccines for Children"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>COVID-19 vaccine is recommended for all children 6 months of age and older.<\/p>\n<p>The #COVID19 vaccines are available at no cost to all children living in the United States.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; admin_label=&#8221;PDF&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#231F20&#8243; custom_padding=&#8221;25px|25px|25px|25px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;\/wp-content\/uploads\/2022\/07\/2022-VACUNAS-RECOMENDADAS-PARA-NIN\u0303OS_final.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Click here to download and print PDF&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;PDF 1&#8243; module_class=&#8221;et-download-button&#8221; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#231F20&#8243; button_bg_color=&#8221;#FFCE00&#8243; button_border_color=&#8221;#FFCE00&#8243; button_icon=&#8221;&#xf019;||fa||900&#8243; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#f5f5f5&#8243; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#f5f5f5&#8243; button_bg_enable_color__hover=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_image src=&#8221;https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/2022-vacunas-recomendadas-para-ninos.png&#8221; alt=&#8221;Vacunas recomendadas para ni\u00f1os&#8221; title_text=&#8221;Vacunas recomendadas para ni\u00f1os&#8221; show_in_lightbox=&#8221;on&#8221; show_bottom_space=&#8221;off&#8221; admin_label=&#8221;1&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se recomienda la vacuna contra el COVID-19 para todos los ni\u00f1os de 6 meses de edad o m\u00e1s.<\/p>\n","protected":false},"author":1,"featured_media":2809,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"project_category":[65],"project_tag":[],"class_list":["post-2813","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-guides"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide: Recommended Vaccines for Children - SOMOS Salud<\/title>\n<meta name=\"description\" content=\"Se recomienda la vacuna contra el COVID-19 para todos los ni\u00f1os de 6 meses de edad o m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide: Recommended Vaccines for Children\" \/>\n<meta property=\"og:description\" content=\"COVID-19 vaccine is recommended for all children 6 months of age and older.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/\" \/>\n<meta property=\"og:site_name\" content=\"SOMOS Salud\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T22:15:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Guide: Recommended Vaccines for Children\" \/>\n<meta name=\"twitter:description\" content=\"COVID-19 vaccine is recommended for all children 6 months of age and older.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/\",\"url\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/\",\"name\":\"Guide: Recommended Vaccines for Children - SOMOS Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/guide_vacunas_recomendadas_para_ninos.jpg\",\"datePublished\":\"2022-07-05T18:36:49+00:00\",\"dateModified\":\"2022-07-06T22:15:57+00:00\",\"description\":\"Se recomienda la vacuna contra el COVID-19 para todos los ni\u00f1os de 6 meses de edad o m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/guide_vacunas_recomendadas_para_ninos.jpg\",\"contentUrl\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/guide_vacunas_recomendadas_para_ninos.jpg\",\"width\":850,\"height\":478,\"caption\":\"Vacunas recomendadas para ni\u00f1os\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/guide-recommended-vaccines-for-children\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/somossalud.us\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guide: Recommended Vaccines for Children\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/somossalud.us\\\/en\\\/\",\"name\":\"SOMOS Salud\",\"description\":\"We take care of each other.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somossalud.us\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide: Recommended Vaccines for Children - SOMOS Salud","description":"Se recomienda la vacuna contra el COVID-19 para todos los ni\u00f1os de 6 meses de edad o m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/","og_locale":"en_US","og_type":"article","og_title":"Guide: Recommended Vaccines for Children","og_description":"COVID-19 vaccine is recommended for all children 6 months of age and older.","og_url":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/","og_site_name":"SOMOS Salud","article_modified_time":"2022-07-06T22:15:57+00:00","og_image":[{"width":850,"height":478,"url":"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Guide: Recommended Vaccines for Children","twitter_description":"COVID-19 vaccine is recommended for all children 6 months of age and older.","twitter_image":"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/","url":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/","name":"Guide: Recommended Vaccines for Children - SOMOS Salud","isPartOf":{"@id":"https:\/\/somossalud.us\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/#primaryimage"},"image":{"@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/#primaryimage"},"thumbnailUrl":"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg","datePublished":"2022-07-05T18:36:49+00:00","dateModified":"2022-07-06T22:15:57+00:00","description":"Se recomienda la vacuna contra el COVID-19 para todos los ni\u00f1os de 6 meses de edad o m\u00e1s.","breadcrumb":{"@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/#primaryimage","url":"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg","contentUrl":"https:\/\/somossalud.us\/wp-content\/uploads\/2022\/02\/guide_vacunas_recomendadas_para_ninos.jpg","width":850,"height":478,"caption":"Vacunas recomendadas para ni\u00f1os"},{"@type":"BreadcrumbList","@id":"https:\/\/somossalud.us\/en\/project\/guide-recommended-vaccines-for-children\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/somossalud.us\/en\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/somossalud.us\/en\/project\/"},{"@type":"ListItem","position":3,"name":"Guide: Recommended Vaccines for Children"}]},{"@type":"WebSite","@id":"https:\/\/somossalud.us\/en\/#website","url":"https:\/\/somossalud.us\/en\/","name":"SOMOS Salud","description":"We take care of each other.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somossalud.us\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/comments?post=2813"}],"version-history":[{"count":7,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/2813\/revisions"}],"predecessor-version":[{"id":3290,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/2813\/revisions\/3290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/media\/2809"}],"wp:attachment":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/media?parent=2813"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project_category?post=2813"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project_tag?post=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}