{"id":4151,"date":"2023-02-27T03:44:50","date_gmt":"2023-02-27T03:44:50","guid":{"rendered":"https:\/\/somossalud.us\/project\/identifica-los-productos-organicos\/"},"modified":"2023-04-28T03:58:42","modified_gmt":"2023-04-28T03:58:42","slug":"identifica-los-productos-organicos","status":"publish","type":"project","link":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/","title":{"rendered":"Identifica los productos org\u00e1nicos"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_title][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; admin_label=&#8221;Social Media&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#231F20&#8243; custom_padding=&#8221;25px|25px|25px|25px|true|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;\/wp-content\/uploads\/2023\/04\/PRODUCTO-ORGANICO-postcard-3inx5in-h.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Descargue aqu\u00ed para imprimir el archivo PDF.&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Version PDF&#8221; module_class=&#8221;et-download-button&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#231F20&#8243; button_bg_color=&#8221;#BCBEC0&#8243; button_border_color=&#8221;#BCBEC0&#8243; button_icon=&#8221;&#xf019;||fa||900&#8243; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#f5f5f5&#8243; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#f5f5f5&#8243; button_bg_enable_color__hover=&#8221;on&#8221;][\/et_pb_button][et_pb_image src=&#8221;https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/productos_organicos_postales_frenteyreverso.png&#8221; alt=&#8221;Identifica los productos org\u00e1nicos&#8221; title_text=&#8221;Identifica los productos org\u00e1nicos&#8221; show_in_lightbox=&#8221;on&#8221; show_bottom_space=&#8221;off&#8221; admin_label=&#8221;Image in jpeg format&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; align=&#8221;center&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica. <\/p>\n","protected":false},"author":1,"featured_media":4145,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"project_category":[61],"project_tag":[],"class_list":["post-4151","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-postcards"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Identifica los productos org\u00e1nicos - SOMOS Salud<\/title>\n<meta name=\"description\" content=\"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Identifica los productos org\u00e1nicos\" \/>\n<meta property=\"og:description\" content=\"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/\" \/>\n<meta property=\"og:site_name\" content=\"SOMOS Salud\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T03:58:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Identifica los productos org\u00e1nicos\" \/>\n<meta name=\"twitter:description\" content=\"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/\",\"url\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/\",\"name\":\"Identifica los productos org\u00e1nicos - SOMOS Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/producto_organico_es.jpg\",\"datePublished\":\"2023-02-27T03:44:50+00:00\",\"dateModified\":\"2023-04-28T03:58:42+00:00\",\"description\":\"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/producto_organico_es.jpg\",\"contentUrl\":\"https:\\\/\\\/somossalud.us\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/producto_organico_es.jpg\",\"width\":850,\"height\":478,\"caption\":\"Identifica los productos org\u00e1nicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/identifica-los-productos-organicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/somossalud.us\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/somossalud.us\\\/en\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Identifica los productos org\u00e1nicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/somossalud.us\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/somossalud.us\\\/en\\\/\",\"name\":\"SOMOS Salud\",\"description\":\"We take care of each other.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/somossalud.us\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Identifica los productos org\u00e1nicos - SOMOS Salud","description":"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/","og_locale":"en_US","og_type":"article","og_title":"Identifica los productos org\u00e1nicos","og_description":"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.","og_url":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/","og_site_name":"SOMOS Salud","article_modified_time":"2023-04-28T03:58:42+00:00","og_image":[{"width":850,"height":478,"url":"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Identifica los productos org\u00e1nicos","twitter_description":"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.","twitter_image":"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/","url":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/","name":"Identifica los productos org\u00e1nicos - SOMOS Salud","isPartOf":{"@id":"https:\/\/somossalud.us\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/#primaryimage"},"image":{"@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/#primaryimage"},"thumbnailUrl":"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg","datePublished":"2023-02-27T03:44:50+00:00","dateModified":"2023-04-28T03:58:42+00:00","description":"Un producto org\u00e1nico es un producto que est\u00e1 libre de sustancias qu\u00edmicas. Si el dinero no es un obst\u00e1culo, procure comprar estos productos de forma org\u00e1nica.","breadcrumb":{"@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/#primaryimage","url":"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg","contentUrl":"https:\/\/somossalud.us\/wp-content\/uploads\/2023\/04\/producto_organico_es.jpg","width":850,"height":478,"caption":"Identifica los productos org\u00e1nicos"},{"@type":"BreadcrumbList","@id":"https:\/\/somossalud.us\/en\/project\/identifica-los-productos-organicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/somossalud.us\/en\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/somossalud.us\/en\/project\/"},{"@type":"ListItem","position":3,"name":"Identifica los productos org\u00e1nicos"}]},{"@type":"WebSite","@id":"https:\/\/somossalud.us\/en\/#website","url":"https:\/\/somossalud.us\/en\/","name":"SOMOS Salud","description":"We take care of each other.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/somossalud.us\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/4151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/comments?post=4151"}],"version-history":[{"count":3,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/4151\/revisions"}],"predecessor-version":[{"id":4156,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project\/4151\/revisions\/4156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/media\/4145"}],"wp:attachment":[{"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/media?parent=4151"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project_category?post=4151"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/somossalud.us\/en\/wp-json\/wp\/v2\/project_tag?post=4151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}